{"id":1378,"date":"2019-03-14T13:12:44","date_gmt":"2019-03-14T12:12:44","guid":{"rendered":"http:\/\/sporting-taekwondo.de\/wordpress\/?p=1378"},"modified":"2019-03-14T13:12:44","modified_gmt":"2019-03-14T12:12:44","slug":"emily-kunz-erkaempft-silber-bei-den-dutch-open","status":"publish","type":"post","link":"http:\/\/sporting-taekwondo.de\/wordpress\/emily-kunz-erkaempft-silber-bei-den-dutch-open\/","title":{"rendered":"Emily Kunz erk\u00e4mpft Silber bei den Dutch Open!!!"},"content":{"rendered":"<pre class=\"western\">\r\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-1379\" src=\"http:\/\/sporting-taekwondo.de\/wordpress\/wp-content\/uploads\/2019\/03\/53556266_2644048512334114_3334607742416453632_n-225x300.jpg\" alt=\"53556266_2644048512334114_3334607742416453632_n\" width=\"225\" height=\"300\" srcset=\"http:\/\/sporting-taekwondo.de\/wordpress\/wp-content\/uploads\/2019\/03\/53556266_2644048512334114_3334607742416453632_n-225x300.jpg 225w, http:\/\/sporting-taekwondo.de\/wordpress\/wp-content\/uploads\/2019\/03\/53556266_2644048512334114_3334607742416453632_n.jpg 720w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\r\n\r\nSPORTING-Taekwondo-Talent Emily Kunz gewinnt nach K\u00e4mpfen gegen die USA, Frankreich, Italien und Belgien hoch verdient die Silbermedaille bei dem begehrten Weltranglistenturnier in den Niederlanden!\r\nIm ersten Kampf gegen eine Amerikanerin die erste Runde noch taktisch vorsichtig herantastend stellte sich im Laufe des Kampfes nach und nach die \u00dcberlegenheit der seit kurzem 12-j\u00e4hrigen heraus. Sie siegte hier mit 16:2 und ging in die n\u00e4chste Runde gegen eine Franz\u00f6sin, welche bereits ebenfalls einen Kampf gewonnen hatte. Hier zwar das Endergebnis betrachtend etwas knapper bestritt Emily auch diese Gegnerin und gewann 35:29 .\r\nMit jeder weiteren Runde steigen die Anzahl der Blessuren , die M\u00fcdigkeit und die Qualit\u00e4t der Kontrahenten. Hier zahlte sich letztlich die gute Arbeit im Training sowie die Vor' und Nacharbeit daheim aus, sodass die SPORTING-K\u00e4mpferin die schwierig zu bezwingende gr\u00f6\u00dfere Italienerin im Halbfinale ebenfalls besiegte.\r\nDas Finale ging leider an eine belgische Sportletin, sodass eine als sehr gut zu bewertende Silbermedaille als Ergebnis blieb.\r\nEin starkes St\u00fcck Arbeit und ein guter Start im Hinblick auf die weiteren globalen Turniere.\r\nEin Riesenerfolg f\u00fcr Emily Kunz in ihrem ersten Kadettenjahr und bei ihrem ersten G-Turnier !\r\nEinen Pokal und die Erstplatzierung holte au\u00dferdem Kerstin Klinkau in der \u00dc-40-Klasse.\r\nInfos zum Verein erh\u00e4lt man unter 0160 9450 4797 oder im Netz auf www.sporting-taekwondo.de\r\n\r\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-1380\" src=\"http:\/\/sporting-taekwondo.de\/wordpress\/wp-content\/uploads\/2019\/03\/54268391_2644048625667436_3291819379838156800_n-225x300.jpg\" alt=\"54268391_2644048625667436_3291819379838156800_n\" width=\"225\" height=\"300\" srcset=\"http:\/\/sporting-taekwondo.de\/wordpress\/wp-content\/uploads\/2019\/03\/54268391_2644048625667436_3291819379838156800_n-225x300.jpg 225w, http:\/\/sporting-taekwondo.de\/wordpress\/wp-content\/uploads\/2019\/03\/54268391_2644048625667436_3291819379838156800_n.jpg 720w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>SPORTING-Taekwondo-Talent Emily Kunz gewinnt nach K\u00e4mpfen gegen die USA, Frankreich, Italien und Belgien hoch verdient die Silbermedaille bei dem begehrten Weltranglistenturnier in den Niederlanden! Im ersten Kampf gegen eine Amerikanerin die erste Runde noch taktisch vorsichtig herantastend stellte sich im<\/p>\n","protected":false},"author":2,"featured_media":1379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[62,12,61],"tags":[234,16],"_links":{"self":[{"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/posts\/1378"}],"collection":[{"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/comments?post=1378"}],"version-history":[{"count":1,"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/posts\/1378\/revisions"}],"predecessor-version":[{"id":1381,"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/posts\/1378\/revisions\/1381"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/media\/1379"}],"wp:attachment":[{"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/media?parent=1378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/categories?post=1378"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sporting-taekwondo.de\/wordpress\/wp-json\/wp\/v2\/tags?post=1378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}